{"id":504,"count":37,"description":"","link":"https:\/\/esentialaroms.com\/pt-pt\/corporalmente\/","name":"CORPORALMENTE","slug":"corporalmente","taxonomy":"product_cat","parent":341,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product_cat\/504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product_cat\/341"}],"wp:post_type":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product?product_cat=504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}