{"id":12834,"date":"2026-05-07T13:06:34","date_gmt":"2026-05-07T11:06:34","guid":{"rendered":"https:\/\/esentialaroms.com\/productos\/hidrolato-de-jara-cistus-ladaniferus-1-litro-2\/"},"modified":"2026-05-07T14:22:18","modified_gmt":"2026-05-07T12:22:18","slug":"hidrolato-de-jara-cistus-ladaniferus-1-litro-2","status":"publish","type":"product","link":"https:\/\/esentialaroms.com\/pt-pt\/productos\/hidrolato-de-jara-cistus-ladaniferus-1-litro-2\/","title":{"rendered":"Hidrolato de JARA (Cistus ladaniferus) 1 litro"},"content":{"rendered":"<div>A \u00e1gua floral ou hidrolato \u00e9 um produto totalmente natural obtido atrav\u00e9s da destila\u00e7\u00e3o a vapor de \u00e1gua de plantas arom\u00e1ticas. Gra\u00e7as a este m\u00e9todo, cont\u00e9m as mol\u00e9culas e fitoativos dessas plantas, que lhe conferem o seu aroma e propriedades \u00fanicas para a pele. &nbsp;<\/div>\n<div>ATEN\u00c7\u00c3O \u00c0S FALSIFICA\u00c7\u00d5ES: s\u00e3o vendidas \u00e1guas florais falsificadas, n\u00e3o se tratando de um produto aut\u00eantico. Tratam-se de \u00e1guas destiladas aromatizadas com subst\u00e2ncias sint\u00e9ticas que n\u00e3o trazem benef\u00edcios \u00e0 pele. Caso utilize \u00e1guas falsificadas, n\u00e3o beneficiar\u00e1 das propriedades que cont\u00e9m uma \u00e1gua floral aut\u00eantica. &nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<div>Hidrolato da planta em flor de esteva proveniente da Agricultura Org\u00e2nica. Recomendado para ativar e fortalecer a microcircula\u00e7\u00e3o cut\u00e2nea e rejuvenescer o rosto. &nbsp;<\/div>\n<div>Facilita a circula\u00e7\u00e3o da energia, ajuda a conserv\u00e1-la e estimula a perce\u00e7\u00e3o sensorial atrav\u00e9s dos 5 sentidos. &nbsp;<\/div>\n<div>Sinta os benef\u00edcios dos hidrolatos aut\u00eanticos na sua pele e nas suas emo\u00e7\u00f5es. &nbsp;<\/div>\n","protected":false},"featured_media":12835,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[308,435],"product_tag":[],"class_list":{"0":"post-12834","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aromaterapia","7":"product_cat-hidrossois-aromaticos-ou-aguas-florais","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product\/12834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=12834"}],"version-history":[{"count":1,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product\/12834\/revisions"}],"predecessor-version":[{"id":12836,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product\/12834\/revisions\/12836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/media\/12835"}],"wp:attachment":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=12834"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=12834"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=12834"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=12834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}