{"id":11841,"date":"2026-05-07T12:46:40","date_gmt":"2026-05-07T10:46:40","guid":{"rendered":"https:\/\/esentialaroms.com\/productos\/aceite-vegetal-virgen-de-tamanu-calofilo-calophyllum-inophyllum-500-ml-2\/"},"modified":"2026-05-07T14:21:55","modified_gmt":"2026-05-07T12:21:55","slug":"aceite-vegetal-virgen-de-tamanu-calofilo-calophyllum-inophyllum-500-ml-2","status":"publish","type":"product","link":"https:\/\/esentialaroms.com\/pt-pt\/productos\/aceite-vegetal-virgen-de-tamanu-calofilo-calophyllum-inophyllum-500-ml-2\/","title":{"rendered":"\u00d3leo v\u00e9g\u00e9tale virgem de TAMANU (Calophyllum inophyllum) 500 ml"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<div>\u00d3leo de tamanu possui propriedades que podem ajudar a reparar a pele com descama\u00e7\u00e3o, acalmar e promover a produ\u00e7\u00e3o de col\u00e1geno. Tem sido tradicionalmente usado para cuidar de cicatrizes p\u00f3s-cir\u00fargicas e desconforto articular. &nbsp;<\/div>\n","protected":false},"featured_media":11842,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[308,522,311,341],"product_tag":[],"class_list":{"0":"post-11841","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aromaterapia","7":"product_cat-atletas","8":"product_cat-oleos-vegetais","9":"product_cat-precisa","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product\/11841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=11841"}],"version-history":[{"count":1,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product\/11841\/revisions"}],"predecessor-version":[{"id":11843,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product\/11841\/revisions\/11843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/media\/11842"}],"wp:attachment":[{"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=11841"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=11841"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=11841"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esentialaroms.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=11841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}