{"id":12820,"date":"2026-05-07T13:06:30","date_gmt":"2026-05-07T11:06:30","guid":{"rendered":"https:\/\/esentialaroms.com\/productos\/hidrolato-de-salvia-salvia-lavandulifolia-subsp-lavandulifolia-1-litro-2\/"},"modified":"2026-05-07T14:22:17","modified_gmt":"2026-05-07T12:22:17","slug":"hidrolato-de-salvia-salvia-lavandulifolia-subsp-lavandulifolia-1-litro-2","status":"publish","type":"product","link":"https:\/\/esentialaroms.com\/fr\/productos\/hidrolato-de-salvia-salvia-lavandulifolia-subsp-lavandulifolia-1-litro-2\/","title":{"rendered":"Hydrolat de SAUGE (Salvia lavandulifolia subsp. lavandulifolia) 1 litre"},"content":{"rendered":"<div>L&rsquo;eau florale ou hydrolat est un produit enti\u00e8rement naturel obtenu par distillation \u00e0 la vapeur d&rsquo;eau de plantes aromatiques. Gr\u00e2ce \u00e0 cette m\u00e9thode, elle contient les mol\u00e9cules et les phytoactifs de ces plantes, qui lui conf\u00e8rent son parfum et ses propri\u00e9t\u00e9s uniques pour la peau. &nbsp;<\/div>\n<div>ATTENTION AUX CONTREFA\u00c7ONS : certains produits sont vendus sous le nom d\u2019 \u00ab eau florale \u00bb alors qu&rsquo;il ne s&rsquo;agit pas de produits authentiques. Ce ne sont que de l&rsquo;eau distill\u00e9e aux ar\u00f4mes, souvent artificielles. Si nous utilisons ces produits qui ne sont pas naturels, nous ne pourrons pas b\u00e9n\u00e9ficier des propri\u00e9t\u00e9s que l&rsquo;eau floral authentique nous apporte. &nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<div>Hydrolat de sommit\u00e9s fleuries de sauge issue de l\u2019Agriculture Biologique. Recommand\u00e9 pour d\u00e9congestionner la peau, r\u00e9guler la production de s\u00e9bum, sp\u00e9cialement en cas de peau mixte-grasse, et \u00e9quilibrer la transpiration de la peau mature et en p\u00e9riode de m\u00e9nopause. &nbsp;<\/div>\n<div>Aide \u00e0 s&rsquo;accepter, \u00e0 assumer les changements et \u00e0 \u00e9quilibrer la partie f\u00e9minine. &nbsp;<\/div>\n<div>Resentez les bienfaits des v\u00e9ritables hydrolats sur votre peau et vos \u00e9motions. &nbsp;<\/div>\n","protected":false},"featured_media":12821,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[307,434],"product_tag":[],"class_list":{"0":"post-12820","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aromatherapie","7":"product_cat-hydrolats-aromatiques-ou-eaux-florales","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product\/12820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/comments?post=12820"}],"version-history":[{"count":1,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product\/12820\/revisions"}],"predecessor-version":[{"id":12822,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product\/12820\/revisions\/12822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/media\/12821"}],"wp:attachment":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/media?parent=12820"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product_brand?post=12820"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product_cat?post=12820"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product_tag?post=12820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}