{"id":12275,"date":"2026-05-07T12:56:25","date_gmt":"2026-05-07T10:56:25","guid":{"rendered":"https:\/\/esentialaroms.com\/productos\/lycorose-50-ml-2\/"},"modified":"2026-05-07T14:22:06","modified_gmt":"2026-05-07T12:22:06","slug":"lycorose-50-ml-2","status":"publish","type":"product","link":"https:\/\/esentialaroms.com\/fr\/productos\/lycorose-50-ml-2\/","title":{"rendered":"LYCOROSE 50 ml"},"content":{"rendered":"<div>Source de lycop\u00e8ne, de carot\u00e9no\u00efdes et O3 v\u00e9g\u00e9tal (33 %) &nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<div>Compl\u00e9ment alimentaire \u00e0 base d&rsquo;huille de rose musqu\u00e9e. &nbsp;<\/div>\n<div>Huile v\u00e9g\u00e9tale vierge de premi\u00e8re pression \u00e0 froid obtenue par des proc\u00e9d\u00e9s m\u00e9caniques \u00e0 partir des fruits les plus rouges s\u00e9lectionn\u00e9s, riches en lycop\u00e8ne et en antioxydants. &nbsp;<\/div>\n","protected":false},"featured_media":12276,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[524,340,322,527,470,355],"product_tag":[],"class_list":{"0":"post-12275","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-anti-age","7":"product_cat-besoins","8":"product_cat-familles","9":"product_cat-la-beaute-de-linterieur","10":"product_cat-lycorose","11":"product_cat-visage","13":"first","14":"instock","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product\/12275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/comments?post=12275"}],"version-history":[{"count":1,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product\/12275\/revisions"}],"predecessor-version":[{"id":12278,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product\/12275\/revisions\/12278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/media\/12276"}],"wp:attachment":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/media?parent=12275"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product_brand?post=12275"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product_cat?post=12275"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product_tag?post=12275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}