{"id":11630,"date":"2026-05-07T12:45:48","date_gmt":"2026-05-07T10:45:48","guid":{"rendered":"https:\/\/esentialaroms.com\/productos\/absoluto-de-violeta-2\/"},"modified":"2026-05-07T14:21:50","modified_gmt":"2026-05-07T12:21:50","slug":"absoluto-de-violeta-2","status":"publish","type":"product","link":"https:\/\/esentialaroms.com\/fr\/productos\/absoluto-de-violeta-2\/","title":{"rendered":"Absolu de VIOLETTE"},"content":{"rendered":"<div>Les huiles essentielles d\u2019ESENTIAL\u2019AR\u00d4MS sont des produits de tr\u00e8s bonne qualit\u00e9, 100% pures et naturelles du fait du processus de s\u00e9lection, de fabrication et de contr\u00f4le de celles-ci. &nbsp;<\/div>\n<div>Une Huile Essentielle H.E.B.B.D., c\u2019est \u00e0 dire une Huile Essentielle Botaniquement et Biochimiquement D\u00e9finie, il s\u2019agit en r\u00e9alit\u00e9 d\u2019une huile essentielle 100% pure et naturelle, obtenue apr\u00e8s distillation compl\u00e8te par extraction de vapeur (sans utilisation d\u2019aucun produit chimique pour son extraction) et apr\u00e8s avoir \u00e9t\u00e9 soumise \u00e0 des contr\u00f4les qualit\u00e9 rigoureux. Les colorants ne sont pas davantage utilis\u00e9s, aucun processus de d\u00e9terp\u00e9nation, rectification ou redistillation n\u2019est appliqu\u00e9. &nbsp;<\/div>\n<div><\/div>\n<div>S\u00c9LECTION DES HUILES ESSENTIELLES H.E.B.D.D. &nbsp;<\/div>\n<div>Les huiles essentielles propos\u00e9es par Esential\u2019Ar\u00f4ms se caract\u00e9risent par le fait qu\u2019elles sont des Huiles Essentielles Botaniquement et Biochimiquement D\u00e9finies (H.E.B.D.D.). Ceci signifie que chacune d\u2019entre elles a \u00e9t\u00e9 s\u00e9lectionn\u00e9e en fonction des param\u00e8tres suivants : &nbsp;<\/div>\n<div>1. Esp\u00e8ce botanique : les plantes utilis\u00e9es sont class\u00e9es botaniquement, nous pouvons donc dire sans aucundoute l\u2019esp\u00e8ce botanique en fonction de la nomenclature internationale. &nbsp;<\/div>\n<div>2. Organe producteur (o. p.) : toutes les parties de la plante n\u2019ont pas la m\u00eame composition. Il est donc n\u00e9cessaire de choisir l\u2019organe (racine, graine, feuilles\u2026) qui, apr\u00e8s distillation, contiendra les substances caract\u00e9ristiques. &nbsp;<\/div>\n<div>3. Sp\u00e9cificit\u00e9 biochimique (s. b.) ou CH\u00c9MOTYPE : apr\u00e8s distillation de l\u2019huile essentielle, il est n\u00e9cessaire de v\u00e9rifier sa composition chimique, qui caract\u00e9rise son utilisation. La v\u00e9rification du bon biotype choisi se fait dans le cadre d\u2019une analyse par chromatographie gazeuse coupl\u00e9e \u00e0 la spectrophotom\u00e9trie de masse. &nbsp;<\/div>\n<div>4. Biotype : en fonction de l\u2019habitat o\u00f9 se d\u00e9veloppe l\u2019esp\u00e8ce botanique (type de terrain, altitude&#8230;), la composition de l\u2019huile essentielle peut varier, la d\u00e9finition du ch\u00e9motype est donc une \u00e9tape essentielle. &nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<div>100 % naturel. &nbsp;<\/div>\n<div>\u00b7 L&rsquo;absolu est obtenu \u00e0 partir de ses feuilles et de ses fleurs, ce qui lui conf\u00e8re un ar\u00f4me herbac\u00e9 et frais. &nbsp;<\/div>\n<div>\u00b7 La dilution permet de percevoir ou d&rsquo;appr\u00e9cier la note florale. &nbsp;<\/div>\n<div>\u00b7 Il poss\u00e8de des propri\u00e9t\u00e9s antiseptiques, d\u00e9congestionnantes pour la peau et l\u00e9g\u00e8rement astringentes, ce qui le rend adapt\u00e9 aux peaux mixtes \u00e0 grasses. \u00bb &nbsp;<\/div>\n","protected":false},"featured_media":11631,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[416,307],"product_tag":[],"class_list":{"0":"post-11630","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-absolus","7":"product_cat-aromatherapie","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product\/11630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/comments?post=11630"}],"version-history":[{"count":1,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product\/11630\/revisions"}],"predecessor-version":[{"id":11633,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product\/11630\/revisions\/11633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/media\/11631"}],"wp:attachment":[{"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/media?parent=11630"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product_brand?post=11630"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product_cat?post=11630"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esentialaroms.com\/fr\/wp-json\/wp\/v2\/product_tag?post=11630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}