{"id":397,"count":0,"description":"","link":"https:\/\/esentialaroms.com\/es\/rosa-mosqueta\/","name":"ROSA MOSQUETA","slug":"rosa-mosqueta","taxonomy":"product_cat","parent":287,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/product_cat\/397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/product_cat\/287"}],"wp:post_type":[{"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/product?product_cat=397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}