{"id":13644,"date":"2026-05-07T13:24:21","date_gmt":"2026-05-07T11:24:21","guid":{"rendered":"https:\/\/esentialaroms.com\/productos\/pino-de-las-landas-pinus-pinaster-o-p-aciculas-10-ml\/"},"modified":"2026-05-07T14:22:36","modified_gmt":"2026-05-07T12:22:36","slug":"pino-de-las-landas-pinus-pinaster-o-p-aciculas-10-ml","status":"publish","type":"product","link":"https:\/\/esentialaroms.com\/es\/productos\/pino-de-las-landas-pinus-pinaster-o-p-aciculas-10-ml\/","title":{"rendered":"Pino de las Landas Pinus pinaster o. p. ac\u00edculas 10 ml"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[370,286],"product_tag":[],"class_list":{"0":"post-13644","1":"product","2":"type-product","3":"status-publish","5":"product_cat-aceites-esenciales","6":"product_cat-aromaterapia","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/product\/13644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/comments?post=13644"}],"version-history":[{"count":0,"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/product\/13644\/revisions"}],"wp:attachment":[{"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/media?parent=13644"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/product_brand?post=13644"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/product_cat?post=13644"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esentialaroms.com\/es\/wp-json\/wp\/v2\/product_tag?post=13644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}