{"id":558,"count":4,"description":"","link":"https:\/\/esentialaroms.com\/en\/new-products\/","name":"New products","slug":"new-products","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product_cat\/558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product?product_cat=558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}