{"id":13948,"date":"2026-05-07T13:30:57","date_gmt":"2026-05-07T11:30:57","guid":{"rendered":"https:\/\/esentialaroms.com\/productos\/benjui-styrax-benzoin-o-p-oleorresina-10-ml-2\/"},"modified":"2026-05-07T14:22:49","modified_gmt":"2026-05-07T12:22:49","slug":"benjui-styrax-benzoin-o-p-oleorresina-10-ml-2","status":"publish","type":"product","link":"https:\/\/esentialaroms.com\/en\/productos\/benjui-styrax-benzoin-o-p-oleorresina-10-ml-2\/","title":{"rendered":"Benju\u00ed Styrax benzoin o. p. oleorresina 10 ml"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[306,418],"product_tag":[],"class_list":{"0":"post-13948","1":"product","2":"type-product","3":"status-publish","5":"product_cat-aromatherapy","6":"product_cat-oleos-essenciais","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product\/13948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/comments?post=13948"}],"version-history":[{"count":0,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product\/13948\/revisions"}],"wp:attachment":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/media?parent=13948"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product_brand?post=13948"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product_cat?post=13948"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product_tag?post=13948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}