{"id":11184,"date":"2026-05-07T12:40:41","date_gmt":"2026-05-07T10:40:41","guid":{"rendered":"https:\/\/esentialaroms.com\/productos\/phytocomplex-repair-2\/"},"modified":"2026-05-07T14:21:41","modified_gmt":"2026-05-07T12:21:41","slug":"phytocomplex-repair-2","status":"publish","type":"product","link":"https:\/\/esentialaroms.com\/en\/productos\/phytocomplex-repair-2\/","title":{"rendered":"Phytocomplex REPAIR"},"content":{"rendered":"<div>Purifying concentrate. &nbsp;<\/div>\n<div>Intensive repair. &nbsp;<\/div>\n<div>Day &amp; night. &nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<div>Purifying serum for skins prope to pimples &nbsp;<\/div>\n","protected":false},"featured_media":11185,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[354,321,339,327,360],"product_tag":[],"class_list":{"0":"post-11184","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-facial","7":"product_cat-families","8":"product_cat-needs","9":"product_cat-phytoserum","10":"product_cat-skin-type","12":"first","13":"instock","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product\/11184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/comments?post=11184"}],"version-history":[{"count":1,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product\/11184\/revisions"}],"predecessor-version":[{"id":11187,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product\/11184\/revisions\/11187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/media\/11185"}],"wp:attachment":[{"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/media?parent=11184"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product_brand?post=11184"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product_cat?post=11184"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/esentialaroms.com\/en\/wp-json\/wp\/v2\/product_tag?post=11184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}